{"id":13291,"date":"2025-08-20T20:16:59","date_gmt":"2025-08-20T20:16:59","guid":{"rendered":"https:\/\/eli-tec.com\/?p=13291"},"modified":"2025-08-22T20:17:59","modified_gmt":"2025-08-22T20:17:59","slug":"guia-completa-sobre-el-anodizado-de-titanio","status":"publish","type":"post","link":"https:\/\/eli-tec.com\/es\/guia-completa-sobre-el-anodizado-de-titanio\/","title":{"rendered":"Gu\u00eda completa para saberlo todo sobre el anodizado de titanio"},"content":{"rendered":"<p><strong>Anodizado de titanio <\/strong>se ha convertido en un proceso esencial de tratamiento de superficies que transforma los componentes ordinarios de titanio en materiales de alto rendimiento con una resistencia superior a la corrosi\u00f3n, una mayor durabilidad y una est\u00e9tica atractiva. La capa de \u00f3xido resultante es protectora en las superficies de titanio y tiene muchas <a href=\"https:\/\/eli-tec.com\/es\/industria\/industria-aeroespacial\/\">aplicaciones en el sector aeroespacial<\/a>de los sectores m\u00e9dico, automovil\u00edstico y de electr\u00f3nica de consumo.<\/p>\n\n\n\n<p>En Elite Mold Tech sabemos que el tratamiento avanzado de superficies es una parte esencial de la producci\u00f3n de componentes de precisi\u00f3n. Se prev\u00e9 que el tama\u00f1o del mercado del titanio anodizado supere los 22.770 millones de d\u00f3lares en 2037, registrando un crecimiento de m\u00e1s del 3,6% CAGR durante el periodo de evaluaci\u00f3n, debido a la creciente popularidad de esta innovadora tecnolog\u00eda.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Inf\u00f3rmese sobre el anodizado de titanio. \u00bfEn qu\u00e9 consiste?<\/strong><\/h2>\n\n\n\n<p><strong>Anodizado de titanio <\/strong>es un proceso de oxidaci\u00f3n electroqu\u00edmica que crea deliberadamente una capa de \u00f3xido controlada en las superficies de titanio. Durante este proceso, el titanio se introduce en una soluci\u00f3n electrol\u00edtica y se conecta a una fuente de energ\u00eda. La oxidaci\u00f3n generada por la corriente el\u00e9ctrica forma una capa de \u00f3xido protectora sobre la superficie. Este tratamiento de la superficie del titanio no s\u00f3lo mejora las propiedades del material, sino que tambi\u00e9n permite fabricar superficies de colores vivos sin utilizar tintes ni pigmentos.<\/p>\n\n\n\n<p>Se realiza sumergiendo piezas de titanio en una soluci\u00f3n electrol\u00edtica con voltaje controlado. Esto deja tras de s\u00ed una capa extremadamente fina de revestimiento de \u00f3xido de titanio (0,1 micras) hasta una capa de protecci\u00f3n m\u00e1s pesada de hasta 25 micras, dependiendo del tipo de anodizado y otros factores relativos a la aplicaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Principales tipos de anodizado de titanio<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Anodizado tipo I<\/strong><\/h3>\n\n\n\n<p>En el anodizado de tipo I, se utiliza una soluci\u00f3n de \u00e1cido cr\u00f3mico. Espesor: Normalmente se utiliza para formar una fina capa de \u00f3xido (de 0,1 a 2 micras). Color: Suele dar lugar a un acabado gris apagado, con opciones de color limitadas. Este tipo se utiliza principalmente en aplicaciones aeroespaciales en las que es fundamental una excelente resistencia a la corrosi\u00f3n y adherencia de la pintura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Anodizado tipo II<\/strong><\/h3>\n\n\n\n<p>El anodizado de titanio de tipo 2 representa la aplicaci\u00f3n industrial m\u00e1s com\u00fan. El anodizado de tipo II utiliza \u00e1cido sulf\u00farico como electrolito. Este m\u00e9todo es popular para anodizar titanio y consiste en aplicar una corriente el\u00e9ctrica para formar una capa de \u00f3xido. El espesor proporciona una capa de \u00f3xido m\u00e1s gruesa (hasta 25 micras).<\/p>\n\n\n\n<p>Este revestimiento aeroespacial de titanio ofrece una extraordinaria resistencia al desgaste y desempe\u00f1a un papel vital cuando es importante reducir la fricci\u00f3n y la abrasi\u00f3n. El proceso de anodizado de tipo 2 refuerza, en lugar de colorear, la capa de \u00f3xido de titanio para producir una superficie de alta fricci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Anodizado tipo III (anodizado en color)<\/strong><\/h3>\n\n\n\n<p>El anodizado de titanio de tipo 3 es popular en las \u00e1reas est\u00e9ticas, al tiempo que conserva los atributos de protecci\u00f3n. El anodizado de titanio de tipo 3 es el llamado anodizado de color, cuyo objetivo es producir colores brillantes cambiando el voltaje utilizado en el proceso de anodizado. Las variaciones en los colores se obtienen mediante la regulaci\u00f3n del grosor de la capa de \u00f3xido, que refleja la refracci\u00f3n de la luz para hacer diferentes colores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Aplicaciones en las distintas industrias<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Industria aeroespacial<\/strong><\/h3>\n\n\n\n<p>El mayor consumidor de productos de titanio anodizado es el sector aeroespacial. La industria de la aviaci\u00f3n en el mercado de titanio anodizado experimentar\u00e1 un mejor crecimiento durante todo el per\u00edodo de previsi\u00f3n y representar\u00e1 la mayor fuente de ingresos de alrededor del 40% debido al creciente consumo de titanio anodizado en la fabricaci\u00f3n de un cuerpo de avi\u00f3n.<\/p>\n\n\n\n<p>El revestimiento de titanio aeroespacial tiene usos como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Piezas estructurales de aeronaves<\/li>\n\n\n\n<li>V\u00e1lvulas, matrices y h\u00e9lices de aviaci\u00f3n<\/li>\n\n\n\n<li>Tuercas y soportes<\/li>\n\n\n\n<li>Escudos y barreras t\u00e9rmicas<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fabricaci\u00f3n m\u00e9dica<\/strong><\/h3>\n\n\n\n<p>El acabado en titanio de los dispositivos m\u00e9dicos ha transformado el campo de la medicina. La superficie de titanio anodizado no es t\u00f3xica ni irritante, por lo que puede utilizarse en contacto directo con c\u00e9lulas sensibles o fluidos corporales.<\/p>\n\n\n\n<p>Algunos de los principales usos m\u00e9dicos son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Implantes ortop\u00e9dicos y pr\u00f3tesis articulares<\/li>\n\n\n\n<li>Implantes y pilares en la boca<\/li>\n\n\n\n<li>Instrumental quir\u00fargico<\/li>\n\n\n\n<li>Componentes prot\u00e9sicos<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Automoci\u00f3n y electr\u00f3nica de consumo<\/strong><\/h3>\n\n\n\n<p>El titanio resistente a la corrosi\u00f3n es un material de alto rendimiento adoptado cada vez en mayor medida por la industria automovil\u00edstica. A\u00fan m\u00e1s, el titanio anodizado encuentra uso en la electr\u00f3nica de consumo en su smartphone, relojes y art\u00edculos de lujo debido a sus propiedades y durabilidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ventajas t\u00e9cnicas del anodizado de titanio<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Protecci\u00f3n superior contra la corrosi\u00f3n<\/strong><\/h3>\n\n\n\n<p>El proceso de anodizado forma una pel\u00edcula de \u00f3xido controlada sobre el titanio mediante un proceso electroqu\u00edmico, produciendo una pel\u00edcula superficial altamente protectora y resistente al desgaste. Este tratamiento de los componentes de titanio mejora la vida \u00fatil de las piezas durante mucho tiempo, sobre todo en entornos corrosivos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Caracter\u00edsticas de desgaste mejoradas<\/strong><\/h3>\n\n\n\n<p>El anodizado de titanio elimina los riesgos de gripado al ofrecer baja fricci\u00f3n y alta dureza en las zonas donde se produce la abrasi\u00f3n de las piezas. Por ello, el titanio anodizado se utiliza mejor donde las maquinarias tienen contacto por deslizamiento o tensi\u00f3n mec\u00e1nica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Biocompatibilidad<\/strong><\/h3>\n\n\n\n<p>La aplicaci\u00f3n m\u00e9dica Opted es un tratamiento biocompatible del titanio que lo hace seguro para su uso sin provocar rechazo en el tejido humano. La superficie anodizada facilita la <a href=\"https:\/\/medschool.cuanschutz.edu\/orthopedics\/clinical-services\/cu-limb-restoration-program\/osseointegration\/what-is-osseointegration\" target=\"_blank\" rel=\"noopener\">osteointegraci\u00f3n<\/a>pero con total biocompatibilidad.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Versatilidad est\u00e9tica<\/strong><\/h3>\n\n\n\n<p>La elecci\u00f3n radica en su capacidad para dar una gran variedad de colores y, debido a ello, se utiliza en proyectos de titanio que necesitan tanto est\u00e9tica como utilidad. Esta doble aplicaci\u00f3n hace que el titanio anodizado sea \u00fatil a nivel industrial y de consumo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Par\u00e1metros de proceso, control de calidad<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Variables cr\u00edticas del proceso<\/strong><\/h3>\n\n\n\n<p>El \u00e9xito del anodizado del titanio requiere un control preciso de varios par\u00e1metros:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Control de tensi\u00f3n: <\/strong>Diferentes voltajes producen diferentes colores y espesores de \u00f3xido\u00a0<\/li>\n\n\n\n<li><strong>Dimensiones: <\/strong>El cambio de dimensiones variar\u00e1 el color y el grosor Revestimiento\u00a0<\/li>\n\n\n\n<li><strong>Composici\u00f3n EE: <\/strong>El tipo de electrolito alterar\u00e1 las propiedades del revestimiento\u00a0<\/li>\n\n\n\n<li><strong>Mantenimiento de la temperatura: <\/strong>Se requiere una temperatura uniforme para obtener resultados uniformes\u00a0<\/li>\n\n\n\n<li><strong>Hora: <\/strong>El tiempo de procesamiento es directamente proporcional al grosor del revestimiento<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Normas de calidad<\/strong><\/h3>\n\n\n\n<p>Para la mayor\u00eda de las l\u00edneas de anodizado de titanio de Tipo 2, la especificaci\u00f3n es AMS 2488. El Tipo 2 tiene la especificaci\u00f3n impulsada por AE International, la asociaci\u00f3n de normas aeroespaciales, y se actualiz\u00f3 por \u00faltima vez en 2019.<\/p>\n\n\n\n<p>En Elite Mold Tech, nos adherimos a estrictas normas de calidad, incluyendo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>AMS 2488 para aplicaciones aeroespaciales<\/li>\n\n\n\n<li>ASTM F86 para componentes de dispositivos m\u00e9dicos<\/li>\n\n\n\n<li>Sistemas de gesti\u00f3n de la calidad ISO 9001<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tendencias del sector y evoluci\u00f3n del mercado<\/strong><\/h2>\n\n\n\n<p>El sector del anodizado de titanio sigue experimentando un fuerte crecimiento impulsado por los avances tecnol\u00f3gicos y la expansi\u00f3n de las aplicaciones. El mercado del titanio anodizado est\u00e1 en continuo crecimiento y es probable que registre una fuerte expansi\u00f3n en breve.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Din\u00e1mica de crecimiento de las regiones<\/strong><\/h3>\n\n\n\n<p>En 2023, el mercado mundial de titanio anodizado fue testigo del papel significativo de las regiones con Am\u00e9rica del Norte contribuyendo 32%, Asia Pac\u00edfico 40%, Europa 18%, Am\u00e9rica Latina 5, y Oriente Medio y \u00c1frica 5.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Aplicaciones emergentes<\/strong><\/h3>\n\n\n\n<p>Siguen apareciendo nuevas aplicaciones en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Componentes de veh\u00edculos el\u00e9ctricos<\/li>\n\n\n\n<li>Los sistemas de energ\u00edas renovables<\/li>\n\n\n\n<li>Engranajes de fabricaci\u00f3n de \u00faltima generaci\u00f3n<\/li>\n\n\n\n<li>Tecnolog\u00eda port\u00e1til<\/li>\n\n\n\n<li>Dificultades y limitaciones<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Complejidad del proceso<\/strong><\/h3>\n\n\n\n<p>El anodizado de titanio requiere equipos y conocimientos especializados. Coste: El anodizado puede ser un proceso bastante caro debido a los materiales y equipos necesarios. Sin embargo, los beneficios a largo plazo suelen compensar el coste inicial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Limitaciones t\u00e9cnicas<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Grosor limitado: <\/strong>Existe un grosor m\u00e1ximo para una capa anodizada, que puede no ser ideal en todas las aplicaciones.\u00a0<\/li>\n\n\n\n<li><strong>Uniformidad del color: <\/strong>Es muy dif\u00edcil producir uniformidad de color porque la operaci\u00f3n de anodizado puede garantizar que no habr\u00e1 disparidades de color.<\/li>\n<\/ul>\n\n\n\n<p>Elite Mold Tech es experta en soluciones de tratamiento total de superficies de titanio para numerosas industrias. Unas instalaciones bien equipadas y nuestra cualificada plantilla de ingenieros garantizan una producci\u00f3n de alta calidad, constante y capaz de cumplir y superar las especificaciones m\u00e1s exigentes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Prestamos servicios:<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aplicaciones de anodizado especiales o personalizadas<\/li>\n\n\n\n<li>Servicios de control de calidad y ensayos<\/li>\n\n\n\n<li>Asesoramiento t\u00e9cnico y mejora de procesos<\/li>\n\n\n\n<li>R\u00e1pida creaci\u00f3n de prototipos y ampliaci\u00f3n de la producci\u00f3n<\/li>\n\n\n\n<li>Consideraciones medioambientales<\/li>\n<\/ul>\n\n\n\n<p>Los modernos procesos de anodizado del titanio hacen hincapi\u00e9 en la responsabilidad medioambiental.&nbsp;<\/p>\n\n\n\n<p><strong>Respetuoso con el medio ambiente: <\/strong>El proceso de anodizado utiliza menos productos qu\u00edmicos t\u00f3xicos que los dem\u00e1s m\u00e9todos de acabado. Esta soluci\u00f3n respetuosa con el medio ambiente se ajusta a las tendencias mundiales de sostenibilidad y, al mismo tiempo, ofrece un alto rendimiento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Perspectivas de futuro del anodizado de titanio&nbsp;<\/strong><\/h2>\n\n\n\n<p>El futuro del anodizado de titanio parece prometedor gracias a los continuos avances tecnol\u00f3gicos. Se prev\u00e9 que el mercado del titanio anodizado registre una tasa de crecimiento muy elevada en el periodo comprendido entre 2025 y 2035, del orden de diez veces.<\/p>\n\n\n\n<p>Las nuevas tendencias son las siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mayor automatizaci\u00f3n y control de procesos<\/li>\n\n\n\n<li>Nuevas f\u00f3rmulas de sistemas h\u00edbridos de recubrimiento electrol\u00edtico<\/li>\n\n\n\n<li>Supervisi\u00f3n y control de calidad en l\u00ednea<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusi\u00f3n<\/strong><\/h2>\n\n\n\n<p>El anodizado del titanio representa una tecnolog\u00eda fundamental que mejora el rendimiento de los materiales en m\u00faltiples sectores. Este tratamiento superficial se ha utilizado en piezas aeroespaciales que tienen que durar mucho tiempo, en implantes m\u00e9dicos que no son perjudiciales para el usuario, un ejemplo de c\u00f3mo se sigue utilizando para seguir impulsando la innovaci\u00f3n y la calidad, y otra raz\u00f3n por la que este vers\u00e1til tratamiento superficial ha desempe\u00f1ado un papel fundamental en la configuraci\u00f3n de nuestro mundo.<\/p>\n\n\n\n<p>En Elite Mold Tech, estamos dispuestos a desarrollar la tecnolog\u00eda de anodizado de titanio, junto con ofrecer a nuestros clientes las mejores soluciones que ayuden a satisfacer sus necesidades. Con la industria a\u00fan en evoluci\u00f3n, realizamos importantes inversiones en los equipos y procesos m\u00e1s modernos para mantenernos a la vanguardia en la prestaci\u00f3n de lo \u00faltimo en servicios de tratamiento de superficies.<\/p>\n\n\n\n<p>El potencial del anodizado de titanio es enorme, y su futuro crece a la par que las nuevas aplicaciones en las que puede utilizarse este material.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Preguntas frecuentes sobre el anodizado de titanio&nbsp;<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. \u00bfCu\u00e1l es el contraste entre el anodizado de titanio de tipo 2 y el de tipo 3?<\/strong><\/h3>\n\n\n\n<p>El anodizado de tipo 2 hace hincapi\u00e9 en aumentar la protecci\u00f3n contra el desgaste y la resistencia a la corrosi\u00f3n y es un acabado gris funcional. El anodizado de tipo 3 crea un color intenso que se utiliza en aplicaciones est\u00e9ticas y, al mismo tiempo, sigue proporcionando protecci\u00f3n. El tipo 2 se utiliza sobre todo en los sectores aeroespacial y m\u00e9dico, mientras que el tipo 3 se emplea en joyer\u00eda y electr\u00f3nica de consumo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. \u00bfCu\u00e1l es la duraci\u00f3n del anodizado del titanio?<\/strong><\/h3>\n\n\n\n<p>El proceso de anodizado depende del tiempo; depende del tipo y del grosor que se necesite. El anodizado de tipo 2 puede llevar entre 30 y 60 minutos, frente a los 15-30 minutos del anodizado con color de tipo 3. Un caso t\u00edpico requiere algunas horas para completar los pasos de anodizado y preparaci\u00f3n, adem\u00e1s del procesamiento posterior, por lo que el tiempo total puede aumentar significativamente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. \u00bfLos colores del titanio anodizado \u00f3nice pierden intensidad con el tiempo?<\/strong><\/h3>\n\n\n\n<p>Cuando se observa este titanio anodizado en condiciones normales, la coloraci\u00f3n es muy estable, pero con el uso prolongado de radiaci\u00f3n UV, temperaturas extremas o entornos abrasivos, es probable que se produzca cierta estabilidad del color. Un tratamiento adecuado y la protecci\u00f3n del medio ambiente ofrecen la posibilidad de mantener los colores intactos durante mucho tiempo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. \u00bfSon seguros los implantes m\u00e9dicos de titanio anodizado?<\/strong><\/h3>\n\n\n\n<p>S\u00ed, el titanio anodizado se adapta perfectamente al cuerpo, e incluso se utiliza habitualmente como implante m\u00e9dico. El procedimiento de anodizado forma una pel\u00edcula de \u00f3xido duradera y no citot\u00f3xica que protege la integraci\u00f3n tisular para disminuir la posibilidad de reacciones adversas. El anodizado del titanio se utiliza para proporcionar superficies a muchos implantes quir\u00fargicos ortop\u00e9dicos y dentales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. \u00bfQu\u00e9 industrias se benefician del anodizado de titanio?<\/strong><\/h3>\n\n\n\n<p>El mayor consumidor es la industria aeroespacial, que consume alrededor del 40% del mercado. La segunda mayor \u00e1rea es la fabricaci\u00f3n de dispositivos m\u00e9dicos, y entre la electr\u00f3nica y los bienes de consumo est\u00e1n los autom\u00f3viles. Las diversas ventajas del anodizado se aplican a cada industria de diversas maneras, como la resistencia a la corrosi\u00f3n, la biocompatibilidad y el aspecto est\u00e9tico.<\/p>","protected":false},"excerpt":{"rendered":"<p>Titanium anodizing has become an essential surface treatment process that transforms ordinary titanium components into high-performance materials with superior corrosion resistance, enhanced durability, and appealing aesthetics. The resulting oxide layer is protective on titanium surfaces and has many applications in the aerospace, medical, automotive, and consumer electronics industries. We know at Elite Mold Tech that [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58],"tags":[],"class_list":["post-13291","post","type-post","status-publish","format-standard","hentry","category-cnc-machining"],"acf":[],"_links":{"self":[{"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/posts\/13291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/comments?post=13291"}],"version-history":[{"count":1,"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/posts\/13291\/revisions"}],"predecessor-version":[{"id":13292,"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/posts\/13291\/revisions\/13292"}],"wp:attachment":[{"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/media?parent=13291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/categories?post=13291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eli-tec.com\/es\/wp-json\/wp\/v2\/tags?post=13291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}